{"id":18860,"date":"2026-02-10T09:27:24","date_gmt":"2026-02-10T09:27:24","guid":{"rendered":"https:\/\/meber2026.graphoservice.it\/product\/maya-650\/"},"modified":"2026-05-15T12:36:26","modified_gmt":"2026-05-15T12:36:26","slug":"maya-650","status":"publish","type":"product","link":"https:\/\/www.meber.it\/es\/product\/maya-650\/","title":{"rendered":"Maya 650"},"content":{"rendered":"<p style=\"\">Dise\u00f1ada para ser un dispositivo esencial para el transporte de pacientes, fabricada en aluminio anodizado ligero. Dispone de 4 palancas (2 traseras y 2 delanteras desmontables) y 2 ruedas fijas de \u00d8 125 mm, es pr\u00e1ctica y f\u00e1cil de usar. Sistema de cierre\/apertura que evita la apertura accidental. Se suministra con bolsa negra de 3 cinturones (Art. 590\/N).<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"\/adm\/Images\/contents\/10G Logo 2019_def.png\" style=\"color: rgb(98, 98, 98); height: 74px; width: 80px;\" \/><br \/>\n<strong>Dispositivo certificado seg\u00fan los est\u00e1ndares armonizados europeos de seguridad UNI EN1865 &#8211; UNI EN1789<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1ada para ser un dispositivo esencial para el transporte de pacientes, fabricada en aluminio anodizado ligero. Dispone de 4 palancas (2 traseras y 2 delanteras desmontables) y 2 ruedas fijas de \u00d8 125 mm, es pr\u00e1ctica y f\u00e1cil de usar. Sistema de cierre\/apertura que evita la apertura accidental. Se suministra con bolsa negra de 3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15382,"parent":0,"menu_order":30001000,"template":"","meta":{"_acf_changed":false,"footnotes":""},"application-tag":[66,81],"class_list":["post-18860","product","type-product","status-publish","has-post-thumbnail","hentry","application-tag-certificado-10g","application-tag-sillas-de-evacuacion"],"acf":[],"dsm_author":{"name":"admeb26","avatar_url":"https:\/\/www.meber.it\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","archive_link":"https:\/\/www.meber.it\/es\/author\/admeb26\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-150x150.jpg","medium":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-300x297.jpg","medium_large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","1536x1536":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","2048x2048":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-post-main-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-portfolio-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-gallery-module-image-portrait":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-400x516.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-image--responsive--desktop":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-image--responsive--tablet":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","et-pb-image--responsive--phone":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya-480x475.jpg","full":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg"},"dsm_comment_count":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maya 650 | silla de traslado plegable | Me.Ber.<\/title>\n<meta name=\"description\" content=\"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meber.it\/es\/product\/maya-650\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maya 650 | silla de traslado plegable | Me.Ber.\" \/>\n<meta property=\"og:description\" content=\"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meber.it\/es\/product\/maya-650\/\" \/>\n<meta property=\"og:site_name\" content=\"Me.Ber.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T12:36:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/\",\"url\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/\",\"name\":\"Maya 650 | silla de traslado plegable | Me.Ber.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/650_sedia_Maya.jpg\",\"datePublished\":\"2026-02-10T09:27:24+00:00\",\"dateModified\":\"2026-05-15T12:36:26+00:00\",\"description\":\"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/650_sedia_Maya.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/650_sedia_Maya.jpg\",\"width\":576,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/maya-650\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meber.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maya 650\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.meber.it\\\/es\\\/\",\"name\":\"Me.Ber.\",\"description\":\"In Case of Emergerncy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meber.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maya 650 | silla de traslado plegable | Me.Ber.","description":"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meber.it\/es\/product\/maya-650\/","og_locale":"es_ES","og_type":"article","og_title":"Maya 650 | silla de traslado plegable | Me.Ber.","og_description":"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.","og_url":"https:\/\/www.meber.it\/es\/product\/maya-650\/","og_site_name":"Me.Ber.","article_modified_time":"2026-05-15T12:36:26+00:00","og_image":[{"width":576,"height":570,"url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/","url":"https:\/\/www.meber.it\/es\/product\/maya-650\/","name":"Maya 650 | silla de traslado plegable | Me.Ber.","isPartOf":{"@id":"https:\/\/www.meber.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/#primaryimage"},"image":{"@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","datePublished":"2026-02-10T09:27:24+00:00","dateModified":"2026-05-15T12:36:26+00:00","description":"Silla de traslado plegable certificada con 2 ruedas fijas, pr\u00e1ctica y f\u00e1cil de usar.","breadcrumb":{"@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meber.it\/es\/product\/maya-650\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/#primaryimage","url":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","contentUrl":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/650_sedia_Maya.jpg","width":576,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/www.meber.it\/es\/product\/maya-650\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meber.it\/es\/"},{"@type":"ListItem","position":2,"name":"Maya 650"}]},{"@type":"WebSite","@id":"https:\/\/www.meber.it\/es\/#website","url":"https:\/\/www.meber.it\/es\/","name":"Me.Ber.","description":"In Case of Emergerncy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meber.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/18860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/18860\/revisions"}],"predecessor-version":[{"id":33469,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/18860\/revisions\/33469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/media\/15382"}],"wp:attachment":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/media?parent=18860"}],"wp:term":[{"taxonomy":"application-tag","embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/application-tag?post=18860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}