{"id":17310,"date":"2026-02-10T09:24:23","date_gmt":"2026-02-10T09:24:23","guid":{"rendered":"https:\/\/meber2026.graphoservice.it\/product\/rescuemed-1343\/"},"modified":"2026-05-04T10:43:22","modified_gmt":"2026-05-04T10:43:22","slug":"rescuemed-1343","status":"publish","type":"product","link":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/","title":{"rendered":"Rescuemed 1343"},"content":{"rendered":"<p class=\"MsoNormal\" style=\" margin: 0cm 0cm 0pt\">Fabricada en tejido rojo resistente a la rotura, la mochila RESCUEMED es ideal para operadores de rescate gracias a su versatilidad y robustez. Amplios bolsillos frontales que facilitan la b\u00fasqueda del material m\u00e1s utilizado, mientras que en el interior, bolsos de colores con asas y sin que permiten el reconocimiento inmediato de los instrumentos necesarios para la intervenci\u00f3n. Dos tiras reflectantes amarillas completan las caracter\u00edsticas de esta mochila de rescate. <strong>Dimensiones: 37 x 52 x 29 cm (LxHxP).<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabricada en tejido rojo resistente a la rotura, la mochila RESCUEMED es ideal para operadores de rescate gracias a su versatilidad y robustez. Amplios bolsillos frontales que facilitan la b\u00fasqueda del material m\u00e1s utilizado, mientras que en el interior, bolsos de colores con asas y sin que permiten el reconocimiento inmediato de los instrumentos necesarios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12821,"parent":0,"menu_order":80000900,"template":"","meta":{"_acf_changed":false,"footnotes":""},"application-tag":[96],"class_list":["post-17310","product","type-product","status-publish","has-post-thumbnail","hentry","application-tag-botiquin-de-primeros-auxilios"],"acf":[],"dsm_author":{"name":"admeb26","avatar_url":"https:\/\/www.meber.it\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","archive_link":"https:\/\/www.meber.it\/es\/author\/admeb26\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-150x150.jpg","medium":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-284x300.jpg","medium_large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","1536x1536":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","2048x2048":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","et-pb-post-main-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-739x675.jpg","et-pb-portfolio-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","et-pb-gallery-module-image-portrait":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-400x516.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","et-pb-image--responsive--desktop":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","et-pb-image--responsive--tablet":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","et-pb-image--responsive--phone":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber-480x507.jpg","full":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg"},"dsm_comment_count":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rescuemed 1343<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rescuemed 1343\" \/>\n<meta property=\"og:description\" content=\"Fabricada en tejido rojo resistente a la rotura, la mochila RESCUEMED es ideal para operadores de rescate gracias a su versatilidad y robustez. Amplios bolsillos frontales que facilitan la b\u00fasqueda del material m\u00e1s utilizado, mientras que en el interior, bolsos de colores con asas y sin que permiten el reconocimiento inmediato de los instrumentos necesarios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/\" \/>\n<meta property=\"og:site_name\" content=\"Me.Ber.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T10:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/\",\"url\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/\",\"name\":\"Rescuemed 1343\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1343_zaino_meber.jpg\",\"datePublished\":\"2026-02-10T09:24:23+00:00\",\"dateModified\":\"2026-05-04T10:43:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1343_zaino_meber.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meber.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1343_zaino_meber.jpg\",\"width\":739,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/product\\\/rescuemed-1343\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meber.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rescuemed 1343\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meber.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.meber.it\\\/es\\\/\",\"name\":\"Me.Ber.\",\"description\":\"In Case of Emergerncy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meber.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rescuemed 1343","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/","og_locale":"es_ES","og_type":"article","og_title":"Rescuemed 1343","og_description":"Fabricada en tejido rojo resistente a la rotura, la mochila RESCUEMED es ideal para operadores de rescate gracias a su versatilidad y robustez. Amplios bolsillos frontales que facilitan la b\u00fasqueda del material m\u00e1s utilizado, mientras que en el interior, bolsos de colores con asas y sin que permiten el reconocimiento inmediato de los instrumentos necesarios [&hellip;]","og_url":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/","og_site_name":"Me.Ber.","article_modified_time":"2026-05-04T10:43:22+00:00","og_image":[{"width":739,"height":780,"url":"https:\/\/meber2026.graphoservice.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/","url":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/","name":"Rescuemed 1343","isPartOf":{"@id":"https:\/\/www.meber.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/#primaryimage"},"image":{"@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","datePublished":"2026-02-10T09:24:23+00:00","dateModified":"2026-05-04T10:43:22+00:00","breadcrumb":{"@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/#primaryimage","url":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","contentUrl":"https:\/\/www.meber.it\/wp-content\/uploads\/2026\/02\/1343_zaino_meber.jpg","width":739,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.meber.it\/es\/product\/rescuemed-1343\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meber.it\/es\/"},{"@type":"ListItem","position":2,"name":"Rescuemed 1343"}]},{"@type":"WebSite","@id":"https:\/\/www.meber.it\/es\/#website","url":"https:\/\/www.meber.it\/es\/","name":"Me.Ber.","description":"In Case of Emergerncy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meber.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/17310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/17310\/revisions"}],"predecessor-version":[{"id":29639,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/product\/17310\/revisions\/29639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/media\/12821"}],"wp:attachment":[{"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/media?parent=17310"}],"wp:term":[{"taxonomy":"application-tag","embeddable":true,"href":"https:\/\/www.meber.it\/es\/wp-json\/wp\/v2\/application-tag?post=17310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}